{"id":22558,"date":"2020-04-14T02:47:00","date_gmt":"2020-04-14T02:47:00","guid":{"rendered":"https:\/\/www.encore-apac.com\/?post_type=case-study&#038;p=22558"},"modified":"2026-01-14T02:51:20","modified_gmt":"2026-01-14T02:51:20","slug":"australia-korea-business-awards","status":"publish","type":"case-study","link":"https:\/\/www.encore-apac.com\/th\/event-planning-resources\/case-studies\/australia-korea-business-awards\/","title":{"rendered":"\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2d\u0e2d\u0e2a\u0e40\u0e15\u0e23\u0e40\u0e25\u0e35\u0e22\u0e40\u0e01\u0e32\u0e2b\u0e25\u0e35"},"content":{"rendered":"<div class=\"custom-block padding--bottom \" > <div class=\"breadcrumb-container\"><div class=\"container\"><nav class=\"breadcrumb\"><div class=\"breadcrumb__home\"><a href=\"https:\/\/www.encore-apac.com\/th\/\"><span class=\"breadcrumb__home__icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M12.1919 7.02537C12.0673 6.99154 11.9325 6.99154 11.8079 7.02537C11.7896 7.03034 11.7359 7.04697 11.5943 7.14418C11.4414 7.24911 11.2514 7.40082 10.9417 7.64961L7.1004 10.7346C6.73765 11.026 6.70113 11.0657 6.68057 11.0936C6.64692 11.139 6.62568 11.1841 6.61376 11.226L6.61333 11.2279C6.61333 11.2279 6.61235 11.2327 6.6115 11.2386C6.60971 11.2509 6.60718 11.2733 6.60506 11.3128C6.60033 11.4008 6.6 11.517 6.6 11.7234V17H9.4V15.0628C9.4 13.6205 10.6465 12.5943 12 12.5943C13.3535 12.5943 14.6 13.6205 14.6 15.0628V17H17.4V11.7234C17.4 11.5175 17.3996 11.4012 17.3948 11.3135C17.3927 11.2742 17.3901 11.2517 17.3883 11.2393C17.3874 11.2333 17.3864 11.2283 17.3864 11.2283L17.3859 11.226C17.3734 11.1821 17.352 11.1373 17.3197 11.0936C17.2991 11.0658 17.2626 11.0261 16.8998 10.7346L13.0598 7.65062C12.7496 7.40152 12.5593 7.24956 12.4062 7.14448C12.2643 7.0471 12.2104 7.03038 12.1919 7.02537ZM19.4 17V11.7234C19.4 11.699 19.4 11.6744 19.4001 11.6498C19.4007 11.3339 19.4013 11.0009 19.3094 10.6784C19.2298 10.3987 19.0999 10.1372 18.9277 9.9043C18.7319 9.63963 18.4719 9.43143 18.2108 9.22229C18.1912 9.20663 18.1717 9.19097 18.1521 9.17528L14.2876 6.07159C14.0103 5.84887 13.7608 5.64843 13.5378 5.49541C13.297 5.33019 13.0335 5.18143 12.7159 5.09521C12.2482 4.96826 11.7517 4.96826 11.284 5.09521C10.9665 5.1814 10.7031 5.33011 10.4626 5.49518C10.2401 5.64788 9.99113 5.84782 9.71468 6.06987L5.84804 9.17528C5.8286 9.19089 5.80915 9.20647 5.78971 9.22204C5.52834 9.43135 5.26837 9.63955 5.07256 9.9043C4.90155 10.1355 4.7704 10.3967 4.69019 10.6784C4.59861 11.0001 4.59927 11.3329 4.5999 11.6467C4.59995 11.6724 4.6 11.698 4.6 11.7234V17H4C3.44772 17 3 17.4477 3 18C3 18.5523 3.44772 19 4 19H20C20.5523 19 21 18.5523 21 18C21 17.4477 20.5523 17 20 17H19.4ZM12.6 17V15.0628C12.6 14.883 12.4138 14.5943 12 14.5943C11.5862 14.5943 11.4 14.883 11.4 15.0628V17H12.6Z\" fill=\"#1F1646\"\/><\/svg> <\/span><span class=\"breadcrumb__home__name\">\u0e2b\u0e19\u0e49\u0e32\u0e41\u0e23\u0e01 <\/span><\/a><span class=\"delimiter\">\/<\/span><\/div><div class=\"breadcrumb__parents\"> <button class=\"text breadcrumb__parents__menu\">&#8230; &nbsp;\/<\/button><\/div><div class=\"breadcrumb__dropdown shadow\"><\/div><div class=\"breadcrumb__current\"><span>\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2d\u0e2d\u0e2a\u0e40\u0e15\u0e23\u0e40\u0e25\u0e35\u0e22\u0e40\u0e01\u0e32\u0e2b\u0e25\u0e35<\/span><\/div><\/nav><\/div><\/div> <\/div><div class=\"custom-block padding--bottom \" > <div class=\"single-resource-hero\" id=\"block_2655e43673de1f35a3461bc37589b161\" data-theme=\"\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e07\u0e48\u0e32\u0e07\u0e32\u0e21\u0e40\u0e17\u0e35\u0e48\u0e22\u0e07\u0e04\u0e37\u0e19\"><div class=\"wrap-shapes\"><div class=\"container\"><div class=\"shapes\"><svg width=\"133\" height=\"91\" viewBox=\"0 0 133 91\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M9.87022 19.5547L19 28.5581L9.87022 37.5615L0.740437 28.5581L9.87022 19.5547Z\" fill=\"var(--color2)\"\/><path d=\"M47.9562 0.000174339L71 22.7251L47.9562 45.45L24.9124 22.7251L47.9562 0.000174339Z\" fill=\"var(--color2)\"\/><path d=\"M38.9138 55.1376L53 69.0288L38.9139 82.92L24.8277 69.0288L38.9138 55.1376Z\" fill=\"var(--color3)\"\/><path d=\"M96.7761 19.3633L133 55.0859L96.776 90.8086L60.5521 55.0859L96.7761 19.3633Z\" fill=\"var(--color1)\"\/><\/svg><\/div><\/div><\/div><div class=\"container container--sm\"><div class=\"row align-center justify-between mobile-reverse\"><div class=\"col-12\"><div class=\"resource-hero__content\"> <h1 class=\"title headline\" data-pinnable>\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2d\u0e2d\u0e2a\u0e40\u0e15\u0e23\u0e40\u0e25\u0e35\u0e22\u0e40\u0e01\u0e32\u0e2b\u0e25\u0e35<\/h1>     <\/div><\/div><div class=\"col-12\"> <div class=\"wrap-image    wrap-video--margin\" id=\"video-block_2655e43673de1f35a3461bc37589b161\" data-pinnable>  <picture><source media=\"(min-width: 1200px)\" srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Australia-Day-Celebration-Korea-2020-1536x1040-1.webp\" type=\"image\/webp\"><source media=\"(min-width: 768px)\" srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Australia-Day-Celebration-Korea-2020-1536x1040-1-1200x813.webp\" type=\"image\/webp\"><source media=\"(min-width: 400px)\" srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Australia-Day-Celebration-Korea-2020-1536x1040-1-768x520.webp\" type=\"image\/webp\"><source srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Australia-Day-Celebration-Korea-2020-1536x1040-1-450x305.webp\" type=\"image\/webp\"><img decoding=\"async\" src=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Australia-Day-Celebration-Korea-2020-1536x1040-1.jpg\" loading=\"lazy\" alt=\"\"><\/picture>   <\/div><\/div><\/div><\/div><\/div><\/div><\/div> <\/div><div class=\"custom-block padding--bottom \" > <div class=\"text-block\"><div class=\"container container--fluid\"><div class=\"\"><h3 class=\"headline title title--\u0e1e.\u0e28.\" data-pinnable>\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d LED \u0e2a\u0e48\u0e2d\u0e07\u0e2a\u0e27\u0e48\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e17\u0e35\u0e48\u0e41\u0e19\u0e48\u0e19\u0e41\u0e1f\u0e49\u0e19\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e2a\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23<\/h3>  <div class=\"text\" data-pinnable><p>\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e14\u0e37\u0e48\u0e21\u0e14\u0e48\u0e4d\u0e32\u0e04\u0e37\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48 Encore \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e02\u0e36\u0e49\u0e19\u0e2a\u0e4d\u0e32\u0e2b\u0e23\u0e31\u0e1a\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 Australia <a href=\"https:\/\/www.encore-apac.com\/th\/our-venue-network\/%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%a9%e0%b8%b1%e0%b8%97%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95-av-%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%ad%e0%b8%b5%e0%b9%80%e0%b8%a7%e0%b8%99-7\/\" target=\"_blank\" rel=\"noopener\">Korea<\/a> Business Awards \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e09\u0e25\u0e34\u0e21\u0e09\u0e25\u0e2d\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e2d\u0e2d\u0e2a\u0e40\u0e15\u0e23\u0e40\u0e25\u0e35\u0e22\u0e41\u0e25\u0e30\u0e40\u0e01\u0e32\u0e2b\u0e25\u0e35\u0e17\u0e35\u0e48\u0e08\u0e31\u0e14\u0e02\u0e36\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2b\u0e49\u0e2d\u0e07\u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c\u0e1a\u0e2d\u0e25\u0e23\u0e39\u0e21\u0e17\u0e35\u0e48\u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c\u0e44\u0e2e\u0e41\u0e2d\u0e17\u0e42\u0e0b\u0e25<\/p>\n<p>\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19 AV \u0e40\u0e15\u0e47\u0e21\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e43\u0e19\u0e01\u0e32\u0e23\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e32\u0e2b\u0e25\u0e35\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e4d\u0e32\u0e04\u0e31\u0e0d\u0e17\u0e32\u0e07\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e2d\u0e19\u0e08\u0e1a\u0e02\u0e2d\u0e07\u0e07\u0e32\u0e19<\/p>\n<p>\u0e08\u0e38\u0e14\u0e2a\u0e19\u0e43\u0e08\u0e02\u0e2d\u0e07\u0e07\u0e32\u0e19\u0e04\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e09\u0e25\u0e34\u0e21\u0e09\u0e25\u0e2d\u0e07\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e2a\u0e40\u0e15\u0e23\u0e40\u0e25\u0e35\u0e22\u0e41\u0e25\u0e30\u0e40\u0e01\u0e32\u0e2b\u0e25\u0e35\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e2a\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e23\u0e25\u0e38\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e19\u0e35\u0e49 \u0e17\u0e35\u0e21\u0e07\u0e32\u0e19 Encore \u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e35\u0e48\u0e08\u0e30\u0e40\u0e19\u0e49\u0e19\u0e44\u0e2d\u0e04\u0e2d\u0e19\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e2a\u0e40\u0e15\u0e23\u0e40\u0e25\u0e35\u0e22\u0e41\u0e25\u0e30\u0e43\u0e0a\u0e49\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e15\u0e32\u0e21\u0e18\u0e35\u0e21\u0e1a\u0e19\u0e1c\u0e19\u0e31\u0e07 LED \u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e08\u0e38\u0e14\u0e42\u0e1f\u0e01\u0e31\u0e2a\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 <\/p>\n<p>\u0e08\u0e34\u0e07\u0e42\u0e08\u0e49\u0e17\u0e31\u0e01\u0e17\u0e32\u0e22\u0e41\u0e02\u0e01\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e48\u0e2d\u0e19\u0e07\u0e32\u0e19\u0e02\u0e13\u0e30\u0e17\u0e35\u0e48\u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32\u0e40\u0e14\u0e34\u0e19\u0e1e\u0e23\u0e21\u0e41\u0e14\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e43\u0e19\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e41\u0e1a\u0e1a<\/p>\n<p>Encore \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e07\u0e32\u0e19\u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49 LED Wall \u0e40\u0e1b\u0e47\u0e19\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c \u0e0b\u0e36\u0e48\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e27\u0e34\u0e18\u0e35\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e2a\u0e39\u0e07 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19 \u0e41\u0e02\u0e01\u0e08\u0e30\u0e40\u0e2b\u0e47\u0e19\u0e01\u0e4d\u0e32\u0e41\u0e1e\u0e07 LED \u0e02\u0e19\u0e32\u0e14\u0e22\u0e31\u0e01\u0e29\u0e4c\u0e02\u0e19\u0e32\u0e14 10 \u0e21. x 4.5 \u0e21. \u0e1a\u0e19\u0e40\u0e27\u0e17\u0e35\u0e01\u0e25\u0e32\u0e07 \u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e16\u0e39\u0e01\u0e43\u0e0a\u0e49\u0e15\u0e25\u0e2d\u0e14\u0e07\u0e32\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e2a\u0e14\u0e07\u0e1c\u0e39\u0e49\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e0a\u0e19\u0e30\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 \u0e1c\u0e19\u0e31\u0e07 LED \u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e07\u0e32\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e23\u0e32\u0e1a\u0e23\u0e37\u0e48\u0e19\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e01\u0e32\u0e23\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a\u0e44\u0e1b\u0e08\u0e19\u0e16\u0e36\u0e07\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25   <\/p>\n<p>\u0e15\u0e2d\u0e19\u0e08\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e02\u0e2d\u0e07\u0e19\u0e31\u0e01\u0e40\u0e15\u0e49\u0e19\u0e40\u0e01\u0e32\u0e2b\u0e25\u0e35\u0e43\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19\u0e17\u0e35\u0e48\u0e41\u0e2a\u0e14\u0e07\u0e01\u0e32\u0e23\u0e40\u0e15\u0e49\u0e19\u0e23\u0e4d\u0e32\u0e41\u0e1a\u0e1a\u0e14\u0e31\u0e49\u0e07\u0e40\u0e14\u0e34\u0e21 \u0e1c\u0e19\u0e31\u0e07 LED \u0e41\u0e2a\u0e14\u0e07\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e17\u0e35\u0e48\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e0a\u0e35\u0e27\u0e32\u0e02\u0e2d\u0e07\u0e27\u0e31\u0e14\u0e40\u0e01\u0e32\u0e2b\u0e25\u0e35\u0e43\u0e19\u0e02\u0e13\u0e30\u0e17\u0e35\u0e48\u0e19\u0e31\u0e01\u0e40\u0e15\u0e49\u0e19\u0e41\u0e2a\u0e14\u0e07 \u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e40\u0e27\u0e17\u0e35\u0e01\u0e47\u0e21\u0e37\u0e14\u0e25\u0e07\u0e40\u0e1c\u0e22\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e04\u0e27\u0e32\u0e21\u0e17\u0e31\u0e19\u0e2a\u0e21\u0e31\u0e22 \u0e19\u0e31\u0e01\u0e40\u0e15\u0e49\u0e19\u0e21\u0e35\u0e44\u0e1f LED \u0e2a\u0e35\u0e40\u0e22\u0e47\u0e1a\u0e40\u0e02\u0e49\u0e32\u0e01\u0e31\u0e1a\u0e15\u0e30\u0e40\u0e02\u0e47\u0e1a\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e22\u0e38\u0e15\u0e34\u0e18\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e17\u0e31\u0e19\u0e2a\u0e21\u0e31\u0e22\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e15\u0e49\u0e19\u0e23\u0e4d\u0e32\u0e41\u0e1a\u0e1a\u0e14\u0e31\u0e49\u0e07\u0e40\u0e14\u0e34\u0e21  <\/p>\n<p>&#8220;\u0e40\u0e23\u0e32\u0e15\u0e37\u0e48\u0e19\u0e40\u0e15\u0e49\u0e19\u0e21\u0e32\u0e01\u0e44\u0e1b\u0e01\u0e27\u0e48\u0e32\u0e19\u0e35\u0e49\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e19\u0e35\u0e49 \u0e1c\u0e19\u0e31\u0e07 LED \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e17\u0e31\u0e19\u0e2a\u0e21\u0e31\u0e22\u0e41\u0e25\u0e30\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19 \u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e14\u0e36\u0e07\u0e14\u0e39\u0e14\u0e41\u0e02\u0e01\u0e15\u0e25\u0e2d\u0e14\u0e17\u0e31\u0e49\u0e07\u0e04\u0e37\u0e19\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e23\u0e30\u0e2b\u0e25\u0e32\u0e14\u0e43\u0e08\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e23\u0e30\u0e2b\u0e25\u0e32\u0e14\u0e43\u0e08 \u0e41\u0e02\u0e01\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e17\u0e31\u0e1a\u0e43\u0e08\u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e02\u0e2d\u0e07\u0e07\u0e32\u0e19\u0e19\u0e35\u0e49 \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e34\u0e48\u0e07\u0e01\u0e32\u0e23\u0e44\u0e14\u0e49\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e01\u0e31\u0e1a\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e01\u0e31\u0e1a\u0e2d\u0e2d\u0e2a\u0e40\u0e15\u0e23\u0e40\u0e25\u0e35\u0e22\u0e42\u0e14\u0e22\u0e15\u0e23\u0e07&#8221;<\/p>\n<\/div><\/div><\/div><\/div> <\/div><div class=\"custom-block padding--bottom \" > <section class=\"image-gallery\"><div class=\"swiper image-gallery-swiper\"><div class=\"swiper-wrapper\"> <div class=\"swiper-slide\" data-pinnable><picture class=\"open-picture js-modal\" data-modal=\"enlarge-picture\" data-image=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Event-Production-Korean-Dancers-1536x1040-1.jpg\" role=\"button\" aria-label=\"Enlarge Picture\"><source srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Event-Production-Korean-Dancers-1536x1040-1-1200x813.webp\" type=\"image\/webp\"><img decoding=\"async\" src=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Event-Production-Korean-Dancers-1536x1040-1.jpg\" loading=\"lazy\" alt=\"\"><\/picture><\/div><div class=\"swiper-slide\" data-pinnable><picture class=\"open-picture js-modal\" data-modal=\"enlarge-picture\" data-image=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Ice-Sculpture-Corporate-Event-Branding-Korea-1536x1040-1.jpg\" role=\"button\" aria-label=\"Enlarge Picture\"><source srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Ice-Sculpture-Corporate-Event-Branding-Korea-1536x1040-1-1200x813.webp\" type=\"image\/webp\"><img decoding=\"async\" src=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Ice-Sculpture-Corporate-Event-Branding-Korea-1536x1040-1.jpg\" loading=\"lazy\" alt=\"\"><\/picture><\/div><div class=\"swiper-slide\" data-pinnable><picture class=\"open-picture js-modal\" data-modal=\"enlarge-picture\" data-image=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Glow-In-The-Dark-Dance-Performance-Korea-1536x1040-1.jpg\" role=\"button\" aria-label=\"Enlarge Picture\"><source srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Glow-In-The-Dark-Dance-Performance-Korea-1536x1040-1-1200x813.webp\" type=\"image\/webp\"><img decoding=\"async\" src=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Glow-In-The-Dark-Dance-Performance-Korea-1536x1040-1.jpg\" loading=\"lazy\" alt=\"\"><\/picture><\/div><div class=\"swiper-slide\" data-pinnable><picture class=\"open-picture js-modal\" data-modal=\"enlarge-picture\" data-image=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Event-Production-Korea-Australia-Business-Awards-1536x1040-1.jpg\" role=\"button\" aria-label=\"Enlarge Picture\"><source srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Event-Production-Korea-Australia-Business-Awards-1536x1040-1-1200x813.webp\" type=\"image\/webp\"><img decoding=\"async\" src=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Event-Production-Korea-Australia-Business-Awards-1536x1040-1.jpg\" loading=\"lazy\" alt=\"\"><\/picture><\/div><div class=\"swiper-slide\" data-pinnable><picture class=\"open-picture js-modal\" data-modal=\"enlarge-picture\" data-image=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Australia-Day-Celebration-Korea-2020-1536x1040-1.jpg\" role=\"button\" aria-label=\"Enlarge Picture\"><source srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Australia-Day-Celebration-Korea-2020-1536x1040-1-1200x813.webp\" type=\"image\/webp\"><img decoding=\"async\" src=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Australia-Day-Celebration-Korea-2020-1536x1040-1.jpg\" loading=\"lazy\" alt=\"\"><\/picture><\/div><div class=\"swiper-slide\" data-pinnable><picture class=\"open-picture js-modal\" data-modal=\"enlarge-picture\" data-image=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/LED-Screen-Corporate-Event-Korea-1536x1040-1.jpg\" role=\"button\" aria-label=\"Enlarge Picture\"><source srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/LED-Screen-Corporate-Event-Korea-1536x1040-1-1200x813.webp\" type=\"image\/webp\"><img decoding=\"async\" src=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/LED-Screen-Corporate-Event-Korea-1536x1040-1.jpg\" loading=\"lazy\" alt=\"\"><\/picture><\/div><div class=\"swiper-slide\" data-pinnable><picture class=\"open-picture js-modal\" data-modal=\"enlarge-picture\" data-image=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Media-Wall-Australia-Korea-Business-Awards-1536x1040-1.jpg\" role=\"button\" aria-label=\"Enlarge Picture\"><source srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Media-Wall-Australia-Korea-Business-Awards-1536x1040-1-1200x813.webp\" type=\"image\/webp\"><img decoding=\"async\" src=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Media-Wall-Australia-Korea-Business-Awards-1536x1040-1.jpg\" loading=\"lazy\" alt=\"\"><\/picture><\/div><div class=\"swiper-slide\" data-pinnable><picture class=\"open-picture js-modal\" data-modal=\"enlarge-picture\" data-image=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Glow-In-The-Dark-Dance-Performance-Korea-1536x1040-2.jpg\" role=\"button\" aria-label=\"Enlarge Picture\"><source srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Glow-In-The-Dark-Dance-Performance-Korea-1536x1040-2-1200x813.webp\" type=\"image\/webp\"><img decoding=\"async\" src=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Glow-In-The-Dark-Dance-Performance-Korea-1536x1040-2.jpg\" loading=\"lazy\" alt=\"\"><\/picture><\/div> <div class=\"swiper-slide\" data-pinnable><picture class=\"open-picture js-modal\" data-modal=\"enlarge-picture\" data-image=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Event-Production-Korean-Dancers-1536x1040-1.jpg\" role=\"button\" aria-label=\"Enlarge Picture\"><source srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Event-Production-Korean-Dancers-1536x1040-1-1200x813.webp\" type=\"image\/webp\"><img decoding=\"async\" src=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Event-Production-Korean-Dancers-1536x1040-1.jpg\" loading=\"lazy\" alt=\"\"><\/picture><\/div><div class=\"swiper-slide\" data-pinnable><picture class=\"open-picture js-modal\" data-modal=\"enlarge-picture\" data-image=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Ice-Sculpture-Corporate-Event-Branding-Korea-1536x1040-1.jpg\" role=\"button\" aria-label=\"Enlarge Picture\"><source srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Ice-Sculpture-Corporate-Event-Branding-Korea-1536x1040-1-1200x813.webp\" type=\"image\/webp\"><img decoding=\"async\" src=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Ice-Sculpture-Corporate-Event-Branding-Korea-1536x1040-1.jpg\" loading=\"lazy\" alt=\"\"><\/picture><\/div><div class=\"swiper-slide\" data-pinnable><picture class=\"open-picture js-modal\" data-modal=\"enlarge-picture\" data-image=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Glow-In-The-Dark-Dance-Performance-Korea-1536x1040-1.jpg\" role=\"button\" aria-label=\"Enlarge Picture\"><source srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Glow-In-The-Dark-Dance-Performance-Korea-1536x1040-1-1200x813.webp\" type=\"image\/webp\"><img decoding=\"async\" src=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Glow-In-The-Dark-Dance-Performance-Korea-1536x1040-1.jpg\" loading=\"lazy\" alt=\"\"><\/picture><\/div><div class=\"swiper-slide\" data-pinnable><picture class=\"open-picture js-modal\" data-modal=\"enlarge-picture\" data-image=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Event-Production-Korea-Australia-Business-Awards-1536x1040-1.jpg\" role=\"button\" aria-label=\"Enlarge Picture\"><source srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Event-Production-Korea-Australia-Business-Awards-1536x1040-1-1200x813.webp\" type=\"image\/webp\"><img decoding=\"async\" src=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Event-Production-Korea-Australia-Business-Awards-1536x1040-1.jpg\" loading=\"lazy\" alt=\"\"><\/picture><\/div><div class=\"swiper-slide\" data-pinnable><picture class=\"open-picture js-modal\" data-modal=\"enlarge-picture\" data-image=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Australia-Day-Celebration-Korea-2020-1536x1040-1.jpg\" role=\"button\" aria-label=\"Enlarge Picture\"><source srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Australia-Day-Celebration-Korea-2020-1536x1040-1-1200x813.webp\" type=\"image\/webp\"><img decoding=\"async\" src=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Australia-Day-Celebration-Korea-2020-1536x1040-1.jpg\" loading=\"lazy\" alt=\"\"><\/picture><\/div><div class=\"swiper-slide\" data-pinnable><picture class=\"open-picture js-modal\" data-modal=\"enlarge-picture\" data-image=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/LED-Screen-Corporate-Event-Korea-1536x1040-1.jpg\" role=\"button\" aria-label=\"Enlarge Picture\"><source srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/LED-Screen-Corporate-Event-Korea-1536x1040-1-1200x813.webp\" type=\"image\/webp\"><img decoding=\"async\" src=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/LED-Screen-Corporate-Event-Korea-1536x1040-1.jpg\" loading=\"lazy\" alt=\"\"><\/picture><\/div><div class=\"swiper-slide\" data-pinnable><picture class=\"open-picture js-modal\" data-modal=\"enlarge-picture\" data-image=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Media-Wall-Australia-Korea-Business-Awards-1536x1040-1.jpg\" role=\"button\" aria-label=\"Enlarge Picture\"><source srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Media-Wall-Australia-Korea-Business-Awards-1536x1040-1-1200x813.webp\" type=\"image\/webp\"><img decoding=\"async\" src=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Media-Wall-Australia-Korea-Business-Awards-1536x1040-1.jpg\" loading=\"lazy\" alt=\"\"><\/picture><\/div><div class=\"swiper-slide\" data-pinnable><picture class=\"open-picture js-modal\" data-modal=\"enlarge-picture\" data-image=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Glow-In-The-Dark-Dance-Performance-Korea-1536x1040-2.jpg\" role=\"button\" aria-label=\"Enlarge Picture\"><source srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Glow-In-The-Dark-Dance-Performance-Korea-1536x1040-2-1200x813.webp\" type=\"image\/webp\"><img decoding=\"async\" src=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Glow-In-The-Dark-Dance-Performance-Korea-1536x1040-2.jpg\" loading=\"lazy\" alt=\"\"><\/picture><\/div> <\/div><\/div><div class=\"container container--sm\"><div class=\"row\"><div class=\"col-md-12\"><div class=\"swiper-elements\"><div class=\"image-gallery-button-prev\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"25\" viewBox=\"0 0 24 25\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M14.7071 6.91203C15.0976 7.30256 15.0976 7.93572 14.7071 8.32625L10.4142 12.6191L14.7071 16.912C15.0976 17.3026 15.0976 17.9357 14.7071 18.3262C14.3166 18.7168 13.6834 18.7168 13.2929 18.3262L8.29289 13.3262C7.90237 12.9357 7.90237 12.3026 8.29289 11.912L13.2929 6.91203C13.6834 6.52151 14.3166 6.52151 14.7071 6.91203Z\"\/><\/svg><\/div><div class=\"image-gallery-pagination\"><\/div><div class=\"image-gallery-button-next\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"25\" viewBox=\"0 0 24 25\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M8.29289 6.91203C7.90237 7.30256 7.90237 7.93572 8.29289 8.32625L12.5858 12.6191L8.29289 16.912C7.90237 17.3026 7.90237 17.9357 8.29289 18.3262C8.68342 18.7168 9.31658 18.7168 9.70711 18.3262L14.7071 13.3262C15.0976 12.9357 15.0976 12.3026 14.7071 11.912L9.70711 6.91203C9.31658 6.52151 8.68342 6.52151 8.29289 6.91203Z\"\/><\/svg><\/div><\/div><\/div><\/div><\/div><dialog class=\"modal image-modal\" id=\"enlarge-picture\" aria-labelledby=\"Big Image Modal\"><button class=\"modal-close js-modal-close\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M6.29289 6.29289C6.68342 5.90237 7.31658 5.90237 7.70711 6.29289L11.9999 10.5857L16.2928 6.29289C16.6833 5.90237 17.3165 5.90237 17.707 6.29289C18.0975 6.68342 18.0975 7.31658 17.707 7.70711L13.4141 11.9999L17.707 16.2928C18.0975 16.6833 18.0975 17.3165 17.707 17.707C17.3165 18.0975 16.6833 18.0975 16.2928 17.707L11.9999 13.4141L7.70711 17.707C7.31658 18.0975 6.68342 18.0975 6.29289 17.707C5.90237 17.3165 5.90237 16.6833 6.29289 16.2928L10.5857 11.9999L6.29289 7.70711C5.90237 7.31658 5.90237 6.68342 6.29289 6.29289Z\" fill=\"white\"\/><\/svg><\/button> <img decoding=\"async\" src=\"\" alt=\"\"><\/dialog><\/section> <\/div><div class=\"custom-block padding--bottom \" > <section class=\"cards-slider\" data-locked><div class=\"container\"><div class=\"row\"><div class=\"col-12\"><div class=\"cards-slider__headline\"> <\/div><\/div><\/div><div class=\"cards-overflow\"> <div class=\"card-fixed-container card-fixed-container--web\"><div class=\"card\"><a href=\"https:\/\/www.encore-apac.com\/th\/event-planning-resources\/case-studies\/\"><div class=\"card__image\"><picture><source srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/DHQANTASforEncore2025-280-scaled-1.webp\" type=\"image\/webp\"><img decoding=\"async\" src=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/DHQANTASforEncore2025-280-scaled-1.jpg\" loading=\"lazy\" alt=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/DHQANTASforEncore2025-280-scaled-1.jpg\"><\/picture><\/div><div class=\"card__text\"><h3 class=\"title  title--xs \">\u0e01\u0e23\u0e13\u0e35\u0e28\u0e36\u0e01\u0e29\u0e32<\/h3><span class=\"btn btn--link\"> <span class=\"btn__text\">\u0e14\u0e39 <\/span> <svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-labelledby=\"svgTitle svgDesc\"><title id=\"svgTitle\">arrow right<\/title><desc id=\"svgDesc\">arrow right icon<\/desc><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M12.2859 7.29993C12.6726 6.90556 13.3057 6.89929 13.7001 7.28593L17.7001 11.2075C17.8919 11.3956 18 11.6529 18 11.9216C18 12.1902 17.8919 12.4476 17.7001 12.6356L13.7001 16.5572C13.3057 16.9438 12.6726 16.9376 12.2859 16.5432C11.8993 16.1488 11.9056 15.5157 12.2999 15.1291L14.5516 12.9216H7C6.44772 12.9216 6 12.4739 6 11.9216C6 11.3693 6.44772 10.9216 7 10.9216H14.5516L12.2999 8.71407C11.9056 8.32743 11.8993 7.6943 12.2859 7.29993Z\"><\/path><\/svg><\/span><\/div><\/a><\/div><\/div> <div class=\"cards-slider-swiper cards-slider-swiper--alt \"><div class=\"swiper-wrapper\"> <div class=\"swiper-slide card-fixed-container card-fixed-container--mobile\"><div class=\"card\"><a href=\"https:\/\/www.encore-apac.com\/th\/event-planning-resources\/case-studies\/\"><div class=\"card__image\"><picture><source srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/DHQANTASforEncore2025-280-scaled-1.webp\" type=\"image\/webp\"><img decoding=\"async\" src=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/DHQANTASforEncore2025-280-scaled-1.jpg\" loading=\"lazy\" alt=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/DHQANTASforEncore2025-280-scaled-1.jpg\"><\/picture><\/div><div class=\"card__text\"><h3 class=\"title  title--xs \">\u0e01\u0e23\u0e13\u0e35\u0e28\u0e36\u0e01\u0e29\u0e32<\/h3><span class=\"btn btn--link\"> <span class=\"btn__text\">\u0e14\u0e39 <\/span> <svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-labelledby=\"svgTitle svgDesc\"><title id=\"svgTitle\">arrow right<\/title><desc id=\"svgDesc\">arrow right icon<\/desc><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M12.2859 7.29993C12.6726 6.90556 13.3057 6.89929 13.7001 7.28593L17.7001 11.2075C17.8919 11.3956 18 11.6529 18 11.9216C18 12.1902 17.8919 12.4476 17.7001 12.6356L13.7001 16.5572C13.3057 16.9438 12.6726 16.9376 12.2859 16.5432C11.8993 16.1488 11.9056 15.5157 12.2999 15.1291L14.5516 12.9216H7C6.44772 12.9216 6 12.4739 6 11.9216C6 11.3693 6.44772 10.9216 7 10.9216H14.5516L12.2999 8.71407C11.9056 8.32743 11.8993 7.6943 12.2859 7.29993Z\"><\/path><\/svg><\/span><\/div><\/a><\/div><\/div>  <div class=\"swiper-slide\"><div class=\"card\"><a href=\"https:\/\/www.encore-apac.com\/th\/event-planning-resources\/case-studies\/a-night-with-the-stars-shines-bright-at-barfoot-thompson-annual-awards\/\"><div class=\"card__image\"><picture><source srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/09\/BarfootandThompsonAwards2024-128-1200x800.webp\" type=\"image\/webp\"><img decoding=\"async\" src=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/09\/BarfootandThompsonAwards2024-128-1200x800.jpg\" loading=\"lazy\" alt=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/09\/BarfootandThompsonAwards2024-128-1200x800.jpg\"><\/picture><\/div><div class=\"card__text\"><h3 class=\"title  title--xs \">A Night with the Stars Shines Bright \u0e17\u0e35\u0e48 Barfoot &amp; Thompson Annual Awards<\/h3> <\/div><\/a><\/div><\/div><div class=\"swiper-slide\"><div class=\"card\"><a href=\"https:\/\/www.encore-apac.com\/th\/event-planning-resources\/case-studies\/adia-2023-the-defence-industrys-event-of-the-year\/\"><div class=\"card__image\"><picture><source srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/ADIA_2023_3.webp\" type=\"image\/webp\"><img decoding=\"async\" src=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/ADIA_2023_3.jpg\" loading=\"lazy\" alt=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/ADIA_2023_3.jpg\"><\/picture><\/div><div class=\"card__text\"><h3 class=\"title  title--xs \">\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e35\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e2a\u0e40\u0e15\u0e23\u0e40\u0e25\u0e35\u0e22<\/h3> <\/div><\/a><\/div><\/div><div class=\"swiper-slide\"><div class=\"card\"><a href=\"https:\/\/www.encore-apac.com\/th\/event-planning-resources\/case-studies\/%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b8%89%e0%b8%a5%e0%b8%b2%e0%b8%94%e0%b8%82%e0%b8%ad%e0%b8%87%e0%b9%81%e0%b8%9a%e0%b8%a3%e0%b8%99%e0%b8%94%e0%b9%8c-%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%80%e0%b8%9b\/\"><div class=\"card__image\"><picture><source srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/OurFutures-Institute-Anti-Vaping-Prevention-_Encore-4-scaled-1-1200x675.webp\" type=\"image\/webp\"><img decoding=\"async\" src=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/OurFutures-Institute-Anti-Vaping-Prevention-_Encore-4-scaled-1-1200x675.jpg\" loading=\"lazy\" alt=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/OurFutures-Institute-Anti-Vaping-Prevention-_Encore-4-scaled-1-1200x675.jpg\"><\/picture><\/div><div class=\"card__text\"><h3 class=\"title  title--xs \">\u0e04\u0e27\u0e32\u0e21\u0e09\u0e25\u0e32\u0e14\u0e02\u0e2d\u0e07\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c: \u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27 OurFutures \u0e1a\u0e23\u0e23\u0e25\u0e38\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22<\/h3> <\/div><\/a><\/div><\/div><div class=\"swiper-slide\"><div class=\"card\"><a href=\"https:\/\/www.encore-apac.com\/th\/event-planning-resources\/case-studies\/taipans-gala-dinner-2025\/\"><div class=\"card__image\"><picture><source srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/Taipans-Gala-Dinner-2025-7-1200x537.webp\" type=\"image\/webp\"><img decoding=\"async\" src=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/Taipans-Gala-Dinner-2025-7-1200x537.jpg\" loading=\"lazy\" alt=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/Taipans-Gala-Dinner-2025-7-1200x537.jpg\"><\/picture><\/div><div class=\"card__text\"><h3 class=\"title  title--xs \">Encore \u0e2a\u0e48\u0e07\u0e21\u0e2d\u0e1a\u0e07\u0e32\u0e19\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 Gala \u0e02\u0e2d\u0e07 Taipans \u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e19\u0e48\u0e32\u0e1b\u0e23\u0e30\u0e17\u0e31\u0e1a\u0e43\u0e08<\/h3> <\/div><\/a><\/div><\/div><div class=\"swiper-slide\"><div class=\"card\"><a href=\"https:\/\/www.encore-apac.com\/th\/event-planning-resources\/case-studies\/encore-%e0%b8%8a%e0%b9%88%e0%b8%a7%e0%b8%a2%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94%e0%b8%95%e0%b8%b1%e0%b8%a7-sofitel-sydney-wentworth-%e0%b8%ad%e0%b8%b5%e0%b8%81%e0%b8%84%e0%b8%a3%e0%b8%b1%e0%b9%89\/\"><div class=\"card__image\"><picture><source srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/Grand-Re-Opening-Sofitel-Sydney-Wentworth-Event-Images__rs-19-1200x800.webp\" type=\"image\/webp\"><img decoding=\"async\" src=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/Grand-Re-Opening-Sofitel-Sydney-Wentworth-Event-Images__rs-19-1200x800.jpg\" loading=\"lazy\" alt=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/Grand-Re-Opening-Sofitel-Sydney-Wentworth-Event-Images__rs-19-1200x800.jpg\"><\/picture><\/div><div class=\"card__text\"><h3 class=\"title  title--xs \">Encore \u0e0a\u0e48\u0e27\u0e22\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27 Sofitel Sydney Wentworth \u0e2d\u0e35\u0e01\u0e04\u0e23\u0e31\u0e49\u0e07\u0e43\u0e19\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e17\u0e35\u0e48\u0e07\u0e14\u0e07\u0e32\u0e21<\/h3> <\/div><\/a><\/div><\/div><div class=\"swiper-slide\"><div class=\"card\"><a href=\"https:\/\/www.encore-apac.com\/th\/event-planning-resources\/case-studies\/encore-%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b9%81%e0%b8%aa%e0%b8%94%e0%b8%87%e0%b8%99%e0%b8%a7%e0%b8%b1%e0%b8%95%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b9%83%e0%b8%99%e0%b8%87%e0%b8%b2%e0%b8%99-pcma-asia-pa\/\"><div class=\"card__image\"><picture><source srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/PCMA-BoE-Encore-Immersive-Experiences-Unveiled-1200x676.webp\" type=\"image\/webp\"><img decoding=\"async\" src=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/PCMA-BoE-Encore-Immersive-Experiences-Unveiled-1200x676.jpg\" loading=\"lazy\" alt=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/PCMA-BoE-Encore-Immersive-Experiences-Unveiled-1200x676.jpg\"><\/picture><\/div><div class=\"card__text\"><h3 class=\"title  title--xs \">Encore \u0e08\u0e31\u0e14\u0e41\u0e2a\u0e14\u0e07\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e43\u0e19\u0e07\u0e32\u0e19 PCMA Asia Pacific&#8217;s &#8216;Unbound&#8217; Conference \u0e17\u0e35\u0e48\u0e2a\u0e34\u0e07\u0e04\u0e42\u0e1b\u0e23\u0e4c<\/h3> <\/div><\/a><\/div><\/div><div class=\"swiper-slide\"><div class=\"card\"><a href=\"https:\/\/www.encore-apac.com\/th\/event-planning-resources\/case-studies\/%e0%b8%a3%e0%b8%b2%e0%b8%87%e0%b8%a7%e0%b8%b1%e0%b8%a5-melbourne-football-club-best-fairest-awards-2024\/\"><div class=\"card__image\"><picture><source srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/MelbourneFCBestFairest2024-KylieIvaPhotography-366--1200x800.webp\" type=\"image\/webp\"><img decoding=\"async\" src=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/MelbourneFCBestFairest2024-KylieIvaPhotography-366--1200x800.jpg\" loading=\"lazy\" alt=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/MelbourneFCBestFairest2024-KylieIvaPhotography-366--1200x800.jpg\"><\/picture><\/div><div class=\"card__text\"><h3 class=\"title  title--xs \">\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 Melbourne Football Club Best &amp; Fairest Awards 2024<\/h3> <\/div><\/a><\/div><\/div><div class=\"swiper-slide\"><div class=\"card\"><a href=\"https:\/\/www.encore-apac.com\/th\/event-planning-resources\/case-studies\/%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%80%e0%b8%94%e0%b8%b4%e0%b8%99%e0%b8%97%e0%b8%b2%e0%b8%87%e0%b8%88%e0%b8%b9%e0%b8%87%e0%b9%83%e0%b8%88%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b9%84%e0%b8%a1%e0%b9%88%e0%b8%a1\/\"><div class=\"card__image\"><picture><source srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/Asian-Paints-India-incentive-journey-across-Australia-New-Zealand-3-1200x800.webp\" type=\"image\/webp\"><img decoding=\"async\" src=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/Asian-Paints-India-incentive-journey-across-Australia-New-Zealand-3-1200x800.jpg\" loading=\"lazy\" alt=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/Asian-Paints-India-incentive-journey-across-Australia-New-Zealand-3-1200x800.jpg\"><\/picture><\/div><div class=\"card__text\"><h3 class=\"title  title--xs \">\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e08\u0e39\u0e07\u0e43\u0e08\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e21\u0e35\u0e43\u0e04\u0e23\u0e2b\u0e22\u0e38\u0e14\u0e22\u0e31\u0e49\u0e07\u0e17\u0e31\u0e48\u0e27\u0e2d\u0e2d\u0e2a\u0e40\u0e15\u0e23\u0e40\u0e25\u0e35\u0e22\u0e41\u0e25\u0e30\u0e19\u0e34\u0e27\u0e0b\u0e35\u0e41\u0e25\u0e19\u0e14\u0e4c\u0e2a\u0e4d\u0e32\u0e2b\u0e23\u0e31\u0e1a Asian Paints India<\/h3> <\/div><\/a><\/div><\/div><div class=\"swiper-slide\"><div class=\"card\"><a href=\"https:\/\/www.encore-apac.com\/th\/event-planning-resources\/case-studies\/%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%88%e0%b9%8d%e0%b8%b2%e0%b8%9b%e0%b8%b5%e0%b8%82%e0%b8%ad%e0%b8%87-hearing-australia\/\"><div class=\"card__image\"><picture><source srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/HEARIN1-1200x800.webp\" type=\"image\/webp\"><img decoding=\"async\" src=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/HEARIN1-1200x800.jpg\" loading=\"lazy\" alt=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/HEARIN1-1200x800.jpg\"><\/picture><\/div><div class=\"card__text\"><h3 class=\"title  title--xs \">\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e1b\u0e23\u0e30\u0e08\u0e4d\u0e32\u0e1b\u0e35\u0e02\u0e2d\u0e07 Hearing Australia<\/h3> <\/div><\/a><\/div><\/div><div class=\"swiper-slide\"><div class=\"card\"><a href=\"https:\/\/www.encore-apac.com\/th\/event-planning-resources\/case-studies\/encore-%e0%b8%82%e0%b8%b1%e0%b8%9a%e0%b9%80%e0%b8%84%e0%b8%a5%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94%e0%b8%95%e0%b8%b1%e0%b8%a7%e0%b9%84\/\"><div class=\"card__image\"><picture><source srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/Event-0278-scaled-1-1200x800.webp\" type=\"image\/webp\"><img decoding=\"async\" src=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/Event-0278-scaled-1-1200x800.jpg\" loading=\"lazy\" alt=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/Event-0278-scaled-1-1200x800.jpg\"><\/picture><\/div><div class=\"card__text\"><h3 class=\"title  title--xs \">Encore \u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e02\u0e2d\u0e07 DEEPAL \u0e17\u0e35\u0e48\u0e2b\u0e32\u0e14\u0e1a\u0e2d\u0e19\u0e44\u0e14<\/h3> <\/div><\/a><\/div><\/div><div class=\"swiper-slide\"><div class=\"card\"><a href=\"https:\/\/www.encore-apac.com\/th\/event-planning-resources\/case-studies\/%e0%b9%80%e0%b8%89%e0%b8%a5%e0%b8%b4%e0%b8%a1%e0%b8%89%e0%b8%a5%e0%b8%ad%e0%b8%87%e0%b8%aa%e0%b8%95%e0%b8%a3%e0%b8%b5%e0%b9%83%e0%b8%99%e0%b8%a7%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%80%e0%b8%97\/\"><div class=\"card__image\"><picture><source srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/Women-in-ICT-Awards-WIICTA-3-scaled-1-1200x799.webp\" type=\"image\/webp\"><img decoding=\"async\" src=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/Women-in-ICT-Awards-WIICTA-3-scaled-1-1200x799.jpg\" loading=\"lazy\" alt=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/Women-in-ICT-Awards-WIICTA-3-scaled-1-1200x799.jpg\"><\/picture><\/div><div class=\"card__text\"><h3 class=\"title  title--xs \">\u0e40\u0e09\u0e25\u0e34\u0e21\u0e09\u0e25\u0e2d\u0e07\u0e2a\u0e15\u0e23\u0e35\u0e43\u0e19\u0e27\u0e07\u0e01\u0e32\u0e23\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e14\u0e49\u0e27\u0e22\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e17\u0e36\u0e48\u0e07\u0e43\u0e19\u0e0b\u0e34\u0e14\u0e19\u0e35\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e42\u0e2d\u0e4a\u0e04\u0e41\u0e25\u0e19\u0e14\u0e4c<\/h3> <\/div><\/a><\/div><\/div><div class=\"swiper-slide\"><div class=\"card\"><a href=\"https:\/\/www.encore-apac.com\/th\/event-planning-resources\/case-studies\/%e0%b8%9c%e0%b8%a5%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%aa%e0%b8%a3%e0%b9%89%e0%b8%b2%e0%b8%87%e0%b8%aa%e0%b8%a3%e0%b8%a3%e0%b8%84%e0%b9%8c%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%81%e0%b8%a5%e0%b9%89%e0%b8%b2\/\"><div class=\"card__image\"><picture><source srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/20241128-Reseller-Awards-NZ-0063-scaled-1-1200x800.webp\" type=\"image\/webp\"><img decoding=\"async\" src=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/20241128-Reseller-Awards-NZ-0063-scaled-1-1200x800.jpg\" loading=\"lazy\" alt=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/20241128-Reseller-Awards-NZ-0063-scaled-1-1200x800.jpg\"><\/picture><\/div><div class=\"card__text\"><h3 class=\"title  title--xs \">\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e17\u0e35\u0e48\u0e01\u0e25\u0e49\u0e32\u0e2b\u0e32\u0e0d\u0e2a\u0e4d\u0e32\u0e2b\u0e23\u0e31\u0e1a Innovation Awards \u0e43\u0e19\u0e0b\u0e34\u0e14\u0e19\u0e35\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e42\u0e2d\u0e4a\u0e04\u0e41\u0e25\u0e19\u0e14\u0e4c<\/h3> <\/div><\/a><\/div><\/div><div class=\"swiper-slide\"><div class=\"card\"><a href=\"https:\/\/www.encore-apac.com\/th\/event-planning-resources\/case-studies\/%e0%b8%a3%e0%b8%b2%e0%b8%87%e0%b8%a7%e0%b8%b1%e0%b8%a5%e0%b8%95%e0%b8%b1%e0%b8%a7%e0%b9%81%e0%b8%97%e0%b8%99%e0%b8%88%e0%b9%8d%e0%b8%b2%e0%b8%ab%e0%b8%99%e0%b9%88%e0%b8%b2%e0%b8%a2%e0%b9%81%e0%b8%ab\/\"><div class=\"card__image\"><picture><source srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/VW-DOTY-April-2025-145-2048x1366-1-1200x800.webp\" type=\"image\/webp\"><img decoding=\"async\" src=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/VW-DOTY-April-2025-145-2048x1366-1-1200x800.jpg\" loading=\"lazy\" alt=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/VW-DOTY-April-2025-145-2048x1366-1-1200x800.jpg\"><\/picture><\/div><div class=\"card__text\"><h3 class=\"title  title--xs \">\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e4d\u0e32\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e35\u0e02\u0e2d\u0e07 Volkswagen 2025<\/h3> <\/div><\/a><\/div><\/div><div class=\"swiper-slide\"><div class=\"card\"><a href=\"https:\/\/www.encore-apac.com\/th\/event-planning-resources\/case-studies\/%e0%b8%a3%e0%b8%b2%e0%b8%87%e0%b8%a7%e0%b8%b1%e0%b8%a5%e0%b8%ad%e0%b8%b8%e0%b8%95%e0%b8%aa%e0%b8%b2%e0%b8%ab%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%9b%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%81%e0%b8%b1\/\"><div class=\"card__image\"><picture><source srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/ADIA-2025-NCCC-22-scaled-1-1200x800.webp\" type=\"image\/webp\"><img decoding=\"async\" src=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/ADIA-2025-NCCC-22-scaled-1-1200x800.jpg\" loading=\"lazy\" alt=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/ADIA-2025-NCCC-22-scaled-1-1200x800.jpg\"><\/picture><\/div><div class=\"card__text\"><h3 class=\"title  title--xs \">\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2d\u0e2d\u0e2a\u0e40\u0e15\u0e23\u0e40\u0e25\u0e35\u0e22 (ADIA) 2025<\/h3> <\/div><\/a><\/div><\/div><div class=\"swiper-slide\"><div class=\"card\"><a href=\"https:\/\/www.encore-apac.com\/th\/event-planning-resources\/case-studies\/encore-%e0%b8%9e%e0%b8%a5%e0%b8%b4%e0%b8%81%e0%b9%82%e0%b8%89%e0%b8%a1%e0%b8%87%e0%b8%b2%e0%b8%99-mcg-for-associations-forum\/\"><div class=\"card__image\"><picture><source srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/Association-Forum_MCG_2025_055-1200x900.webp\" type=\"image\/webp\"><img decoding=\"async\" src=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/Association-Forum_MCG_2025_055-1200x900.jpg\" loading=\"lazy\" alt=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/Association-Forum_MCG_2025_055-1200x900.jpg\"><\/picture><\/div><div class=\"card__text\"><h3 class=\"title  title--xs \">Encore \u0e1e\u0e25\u0e34\u0e01\u0e42\u0e09\u0e21\u0e07\u0e32\u0e19 MCG for Associations Forum<\/h3> <\/div><\/a><\/div><\/div><div class=\"swiper-slide\"><div class=\"card\"><a href=\"https:\/\/www.encore-apac.com\/th\/event-planning-resources\/case-studies\/million-dollar-lunch-2025-%e0%b8%a1%e0%b8%b2%e0%b8%aa%e0%b9%80%e0%b8%95%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b8%84%e0%b8%a5%e0%b8%b2%e0%b8%aa%e0%b9%83%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%ad%e0%b8%ad\/\"><div class=\"card__image\"><picture><source srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/Million-Dollar-Lunch-2025-Encore-6-scaled-1-1200x800.webp\" type=\"image\/webp\"><img decoding=\"async\" src=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/Million-Dollar-Lunch-2025-Encore-6-scaled-1-1200x800.jpg\" loading=\"lazy\" alt=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/Million-Dollar-Lunch-2025-Encore-6-scaled-1-1200x800.jpg\"><\/picture><\/div><div class=\"card__text\"><h3 class=\"title  title--xs \">Million Dollar Lunch 2025 &#8211; \u0e21\u0e32\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e04\u0e25\u0e32\u0e2a\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e35\u0e48\u0e23\u0e32\u0e1a\u0e23\u0e37\u0e48\u0e19<\/h3> <\/div><\/a><\/div><\/div><div class=\"swiper-slide\"><div class=\"card\"><a href=\"https:\/\/www.encore-apac.com\/th\/event-planning-resources\/case-studies\/%e0%b9%80%e0%b8%9b%e0%b8%a5%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%b1%e0%b8%a1%e0%b8%a1%e0%b8%99%e0%b8%b2%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%80%e0%b8%9b\/\"><div class=\"card__image\"><picture><source srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/Encore_Amway_Gala_Dinner_259-scaled-1.webp\" type=\"image\/webp\"><img decoding=\"async\" src=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/Encore_Amway_Gala_Dinner_259-scaled-1.jpg\" loading=\"lazy\" alt=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/Encore_Amway_Gala_Dinner_259-scaled-1.jpg\"><\/picture><\/div><div class=\"card__text\"><h3 class=\"title  title--xs \">\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e19\u0e4d\u0e32\u0e02\u0e2d\u0e07\u0e41\u0e2d\u0e21\u0e40\u0e27\u0e22\u0e4c\u0e08\u0e35\u0e19\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e08\u0e0d\u0e20\u0e31\u0e22\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e15\u0e37\u0e48\u0e19\u0e40\u0e15\u0e49\u0e19\u0e02\u0e2d\u0e07\u0e19\u0e34\u0e27\u0e0b\u0e35\u0e41\u0e25\u0e19\u0e14\u0e4c<\/h3> <\/div><\/a><\/div><\/div><div class=\"swiper-slide\"><div class=\"card\"><a href=\"https:\/\/www.encore-apac.com\/th\/event-planning-resources\/case-studies\/encore-%e0%b9%80%e0%b8%9b%e0%b8%a5%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%99%e0%b8%ad%e0%b8%b2%e0%b8%84%e0%b8%b2%e0%b8%a3%e0%b8%9c%e0%b8%b9%e0%b9%89%e0%b9%82%e0%b8%94%e0%b8%a2%e0%b8%aa%e0%b8%b2%e0%b8%a3\/\"><div class=\"card__image\"><picture><source srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/240503_HelloWorld_OMC_Day_2_Gala_Dinner-234-scaled-1-1200x800.webp\" type=\"image\/webp\"><img decoding=\"async\" src=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/240503_HelloWorld_OMC_Day_2_Gala_Dinner-234-scaled-1-1200x800.jpg\" loading=\"lazy\" alt=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/240503_HelloWorld_OMC_Day_2_Gala_Dinner-234-scaled-1-1200x800.jpg\"><\/picture><\/div><div class=\"card__text\"><h3 class=\"title  title--xs \">Encore \u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1c\u0e39\u0e49\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e0b\u0e34\u0e14\u0e19\u0e35\u0e22\u0e4c\u0e2a\u0e4d\u0e32\u0e2b\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e01\u0e32\u0e25\u0e48\u0e32\u0e2d\u0e31\u0e19\u0e15\u0e23\u0e30\u0e01\u0e32\u0e23\u0e15\u0e32\u0e02\u0e2d\u0e07 Helloworld Travel<\/h3> <\/div><\/a><\/div><\/div><div class=\"swiper-slide\"><div class=\"card\"><a href=\"https:\/\/www.encore-apac.com\/th\/event-planning-resources\/case-studies\/%e0%b8%81%e0%b8%a5%e0%b9%89%e0%b8%b2%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%88%e0%b8%b0%e0%b8%95%e0%b8%b7%e0%b9%88%e0%b8%99%e0%b8%95%e0%b8%b2%e0%b8%95%e0%b8%b7%e0%b9%88%e0%b8%99%e0%b9%83%e0%b8%88-%e0%b8%81\/\"><div class=\"card__image\"><picture><source srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/Top-Secret-Dinner-1-1200x800.webp\" type=\"image\/webp\"><img decoding=\"async\" src=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/Top-Secret-Dinner-1-1200x800.jpg\" loading=\"lazy\" alt=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/Top-Secret-Dinner-1-1200x800.jpg\"><\/picture><\/div><div class=\"card__text\"><h3 class=\"title  title--xs \">\u0e01\u0e25\u0e49\u0e32\u0e17\u0e35\u0e48\u0e08\u0e30\u0e15\u0e37\u0e48\u0e19\u0e15\u0e32\u0e15\u0e37\u0e48\u0e19\u0e43\u0e08: \u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e02\u0e2d\u0e07 Encore \u0e17\u0e35\u0e48 Top Secret Showcase<\/h3> <\/div><\/a><\/div><\/div><div class=\"swiper-slide\"><div class=\"card\"><a href=\"https:\/\/www.encore-apac.com\/th\/event-planning-resources\/case-studies\/flinders-university-%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94%e0%b8%95%e0%b8%b1%e0%b8%a7%e0%b8%ad%e0%b8%b2%e0%b8%84%e0%b8%b2%e0%b8%a3%e0%b8%a7%e0%b8%b4%e0%b8%88%e0%b8%b1%e0%b8%a2%e0%b8%94%e0%b9%89%e0%b8%b2\/\"><div class=\"card__image\"><picture><source srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/Flinders-University-Health-and-Medical-Research-Building-Launch-Event-4-1200x799.webp\" type=\"image\/webp\"><img decoding=\"async\" src=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/Flinders-University-Health-and-Medical-Research-Building-Launch-Event-4-1200x799.jpg\" loading=\"lazy\" alt=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/10\/Flinders-University-Health-and-Medical-Research-Building-Launch-Event-4-1200x799.jpg\"><\/picture><\/div><div class=\"card__text\"><h3 class=\"title  title--xs \">Flinders University \u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e14\u0e49\u0e32\u0e19\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32 280 \u0e25\u0e49\u0e32\u0e19\u0e14\u0e2d\u0e25\u0e25\u0e32\u0e23\u0e4c\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e42\u0e14\u0e22\u0e1c\u0e39\u0e49\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e02\u0e2d\u0e07 Encore<\/h3> <\/div><\/a><\/div><\/div><div class=\"swiper-slide\"><div class=\"card\"><a href=\"https:\/\/www.encore-apac.com\/th\/event-planning-resources\/case-studies\/encore-%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94%e0%b8%95%e0%b8%b1%e0%b8%a7-led-odyssey-%e0%b8%aa%e0%b9%8d%e0%b8%b2%e0%b8%ab%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9b%e0%b8%a3%e0%b8%b0\/\"><div class=\"card__image\"><picture><source srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2024\/06\/20240506_231450107_iOS.webp\" type=\"image\/webp\"><img decoding=\"async\" src=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2024\/06\/20240506_231450107_iOS.jpg\" loading=\"lazy\" alt=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2024\/06\/20240506_231450107_iOS.jpg\"><\/picture><\/div><div class=\"card__text\"><h3 class=\"title  title--xs \">Encore \u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27 LED odyssey \u0e2a\u0e4d\u0e32\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e41\u0e25\u0e30\u0e2d\u0e27\u0e01\u0e32\u0e28<\/h3> <\/div><\/a><\/div><\/div><div class=\"swiper-slide\"><div class=\"card\"><a href=\"https:\/\/www.encore-apac.com\/th\/event-planning-resources\/case-studies\/qantas-platinum-member-experience-doltone-55-years-celebration\/\"><div class=\"card__image\"><picture><source srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/11\/DHQANTASforEncore2025-105-1200x800.webp\" type=\"image\/webp\"><img decoding=\"async\" src=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/11\/DHQANTASforEncore2025-105-1200x800.jpg\" loading=\"lazy\" alt=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/11\/DHQANTASforEncore2025-105-1200x800.jpg\"><\/picture><\/div><div class=\"card__text\"><h3 class=\"title  title--xs \">\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e41\u0e04\u0e27\u0e19\u0e15\u0e31\u0e2a\u0e41\u0e1e\u0e25\u0e17\u0e34\u0e19\u0e31\u0e21<\/h3> <\/div><\/a><\/div><\/div><div class=\"swiper-slide\"><div class=\"card\"><a href=\"https:\/\/www.encore-apac.com\/th\/event-planning-resources\/case-studies\/master-builders-centenary\/\"><div class=\"card__image\"><picture><source srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/11\/IMG_3592_scaled-1200x675.webp\" type=\"image\/webp\"><img decoding=\"async\" src=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/11\/IMG_3592_scaled-1200x675.jpg\" loading=\"lazy\" alt=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/11\/IMG_3592_scaled-1200x675.jpg\"><\/picture><\/div><div class=\"card__text\"><h3 class=\"title  title--xs \">\u0e1e\u0e25\u0e34\u0e01\u0e2a\u0e04\u0e23\u0e34\u0e1b\u0e15\u0e4c: Encore \u0e04\u0e34\u0e14\u0e04\u0e49\u0e19\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e07\u0e32\u0e19\u0e01\u0e32\u0e25\u0e48\u0e32\u0e43\u0e2b\u0e21\u0e48\u0e2a\u0e4d\u0e32\u0e2b\u0e23\u0e31\u0e1a\u0e27\u0e31\u0e19\u0e04\u0e23\u0e1a\u0e23\u0e2d\u0e1a 100 \u0e1b\u0e35\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e23\u0e21\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23<\/h3> <\/div><\/a><\/div><\/div><div class=\"swiper-slide\"><div class=\"card\"><a href=\"https:\/\/www.encore-apac.com\/th\/event-planning-resources\/case-studies\/disruption-conference-2025-for-domestic-violence-prevention\/\"><div class=\"card__image\"><picture><source srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/11\/Disruption-Conference-2025-DVPC-Sea-World_Encore-16.webp\" type=\"image\/webp\"><img decoding=\"async\" src=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/11\/Disruption-Conference-2025-DVPC-Sea-World_Encore-16.jpg\" loading=\"lazy\" alt=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/11\/Disruption-Conference-2025-DVPC-Sea-World_Encore-16.jpg\"><\/picture><\/div><div class=\"card__text\"><h3 class=\"title  title--xs \">Disruption Conference 2025 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e04\u0e27\u0e32\u0e21\u0e23\u0e38\u0e19\u0e41\u0e23\u0e07\u0e43\u0e19\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27<\/h3> <\/div><\/a><\/div><\/div><div class=\"swiper-slide\"><div class=\"card\"><a href=\"https:\/\/www.encore-apac.com\/th\/event-planning-resources\/case-studies\/vip-showcase-for-pan-pacific-orchard-themed-eden-after-dark\/\"><div class=\"card__image\"><picture><source srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/12\/PAN_0250_MZ8_9072.webp\" type=\"image\/webp\"><img decoding=\"async\" src=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/12\/PAN_0250_MZ8_9072.jpg\" loading=\"lazy\" alt=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/12\/PAN_0250_MZ8_9072.jpg\"><\/picture><\/div><div class=\"card__text\"><h3 class=\"title  title--xs \">Encore \u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a VIP Showcase \u0e2a\u0e4d\u0e32\u0e2b\u0e23\u0e31\u0e1a Pan Pacific Orchard \u0e43\u0e19\u0e18\u0e35\u0e21 &#8220;Eden After Dark&#8221;<\/h3> <\/div><\/a><\/div><\/div><div class=\"swiper-slide\"><div class=\"card\"><a href=\"https:\/\/www.encore-apac.com\/th\/event-planning-resources\/case-studies\/w-singapore-sentosa-cove-w-presents-ft-dj-pippi-ciez\/\"><div class=\"card__image\"><picture><source srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/W-PRESENTS-ft-DJ-Pippi-Ciez-W-Singapore-Sentosa-Cove_-ENCORE-14-e1767830171353.webp\" type=\"image\/webp\"><img decoding=\"async\" src=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/W-PRESENTS-ft-DJ-Pippi-Ciez-W-Singapore-Sentosa-Cove_-ENCORE-14-e1767830171353.jpg\" loading=\"lazy\" alt=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/W-PRESENTS-ft-DJ-Pippi-Ciez-W-Singapore-Sentosa-Cove_-ENCORE-14-e1767830171353.jpg\"><\/picture><\/div><div class=\"card__text\"><h3 class=\"title  title--xs \">W Singapore Reimagined: Encore \u0e21\u0e2d\u0e1a\u0e07\u0e32\u0e19 W PRESENTS \u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e15\u0e37\u0e48\u0e19\u0e15\u0e32\u0e15\u0e37\u0e48\u0e19\u0e43\u0e08\u0e17\u0e35\u0e48 WOOBAR<\/h3> <\/div><\/a><\/div><\/div><div class=\"swiper-slide\"><div class=\"card\"><a href=\"https:\/\/www.encore-apac.com\/th\/event-planning-resources\/case-studies\/the-westin-singapore-turns-10-and-partners-with-encore-for-luxe-vip-gala-nights\/\"><div class=\"card__image\"><picture><source srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Westin-Singapore-Hotel-Turns-10-_Produced-by-Encore-Singapore-2-1200x800.webp\" type=\"image\/webp\"><img decoding=\"async\" src=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Westin-Singapore-Hotel-Turns-10-_Produced-by-Encore-Singapore-2-1200x800.jpg\" loading=\"lazy\" alt=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Westin-Singapore-Hotel-Turns-10-_Produced-by-Encore-Singapore-2-1200x800.jpg\"><\/picture><\/div><div class=\"card__text\"><h3 class=\"title  title--xs \">\u0e40\u0e14\u0e2d\u0e30 \u0e40\u0e27\u0e2a\u0e17\u0e34\u0e19 \u0e2a\u0e34\u0e07\u0e04\u0e42\u0e1b\u0e23\u0e4c \u0e04\u0e23\u0e1a\u0e23\u0e2d\u0e1a 10 \u0e1b\u0e35 \u0e41\u0e25\u0e30\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e01\u0e31\u0e1a Encore \u0e2a\u0e4d\u0e32\u0e2b\u0e23\u0e31\u0e1a Luxe VIP Gala Nights<\/h3> <\/div><\/a><\/div><\/div><div class=\"swiper-slide\"><div class=\"card\"><a href=\"https:\/\/www.encore-apac.com\/th\/event-planning-resources\/case-studies\/light-the-way-uc-berkeleys-asia-roadshow-shines-in-hong-kong\/\"><div class=\"card__image\"><picture><source srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/UC-Berkley-Light-the-Way-at-Grand-Hyatt-Hong-Kong-2-1200x1500.webp\" type=\"image\/webp\"><img decoding=\"async\" src=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/UC-Berkley-Light-the-Way-at-Grand-Hyatt-Hong-Kong-2-1200x1500.jpg\" loading=\"lazy\" alt=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/UC-Berkley-Light-the-Way-at-Grand-Hyatt-Hong-Kong-2-1200x1500.jpg\"><\/picture><\/div><div class=\"card__text\"><h3 class=\"title  title--xs \">Light the Way: \u0e07\u0e32\u0e19\u0e42\u0e23\u0e14\u0e42\u0e0a\u0e27\u0e4c\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22\u0e02\u0e2d\u0e07 UC Berkeley \u0e40\u0e1b\u0e25\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e22\u0e43\u0e19\u0e2e\u0e48\u0e2d\u0e07\u0e01\u0e07<\/h3> <\/div><\/a><\/div><\/div><div class=\"swiper-slide\"><div class=\"card\"><a href=\"https:\/\/www.encore-apac.com\/th\/event-planning-resources\/case-studies\/fashion-for-cancer-singapore-2024\/\"><div class=\"card__image\"><picture><source srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/11\/Fashion-for-Cancer-Singapore-2024-wide-angle-shot-1-1-scaled-1-1200x800.webp\" type=\"image\/webp\"><img decoding=\"async\" src=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/11\/Fashion-for-Cancer-Singapore-2024-wide-angle-shot-1-1-scaled-1-1200x800.jpg\" loading=\"lazy\" alt=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/11\/Fashion-for-Cancer-Singapore-2024-wide-angle-shot-1-1-scaled-1-1200x800.jpg\"><\/picture><\/div><div class=\"card__text\"><h3 class=\"title  title--xs \">Hope \u0e02\u0e36\u0e49\u0e19\u0e23\u0e31\u0e19\u0e40\u0e27\u0e22\u0e4c\u0e17\u0e35\u0e48 Fashion for Cancer Singapore<\/h3> <\/div><\/a><\/div><\/div><div class=\"swiper-slide\"><div class=\"card\"><a href=\"https:\/\/www.encore-apac.com\/th\/event-planning-resources\/case-studies\/creating-a-hybrid-celebration-for-the-university-of-sydneys-graduates\/\"><div class=\"card__image\"><picture><source srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/11\/Uni-Syd-Graduation-Live-Stream-Mock-1-2048x1403-1-1200x822.webp\" type=\"image\/webp\"><img decoding=\"async\" src=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/11\/Uni-Syd-Graduation-Live-Stream-Mock-1-2048x1403-1-1200x822.jpg\" loading=\"lazy\" alt=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/11\/Uni-Syd-Graduation-Live-Stream-Mock-1-2048x1403-1-1200x822.png\"><\/picture><\/div><div class=\"card__text\"><h3 class=\"title  title--xs \">\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e09\u0e25\u0e34\u0e21\u0e09\u0e25\u0e2d\u0e07\u0e41\u0e1a\u0e1a\u0e44\u0e2e\u0e1a\u0e23\u0e34\u0e14\u0e2a\u0e4d\u0e32\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e2a\u0e4d\u0e32\u0e40\u0e23\u0e47\u0e08\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e08\u0e32\u0e01\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e0b\u0e34\u0e14\u0e19\u0e35\u0e22\u0e4c<\/h3> <\/div><\/a><\/div><\/div><div class=\"swiper-slide\"><div class=\"card\"><a href=\"https:\/\/www.encore-apac.com\/th\/event-planning-resources\/case-studies\/light-up-live-a-stellar-showcase-at-the-westin-singapore\/\"><div class=\"card__image\"><picture><source srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/LAM_2817-1536x1024-1-1200x800.webp\" type=\"image\/webp\"><img decoding=\"async\" src=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/LAM_2817-1536x1024-1-1200x800.jpg\" loading=\"lazy\" alt=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/LAM_2817-1536x1024-1-1200x800.jpg\"><\/picture><\/div><div class=\"card__text\"><h3 class=\"title  title--xs \">Light Up Live: \u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e01\u0e17\u0e35\u0e48 The Westin Singapore<\/h3> <\/div><\/a><\/div><\/div><div class=\"swiper-slide\"><div class=\"card\"><a href=\"https:\/\/www.encore-apac.com\/th\/event-planning-resources\/case-studies\/icici-prudential-life-gala-hits-a-six-at-crown-melbourne\/\"><div class=\"card__image\"><picture><source srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2024\/03\/Image-186-min-1200x800.webp\" type=\"image\/webp\"><img decoding=\"async\" src=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2024\/03\/Image-186-min-1200x800.jpg\" loading=\"lazy\" alt=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2024\/03\/Image-186-min-1200x800.jpg\"><\/picture><\/div><div class=\"card__text\"><h3 class=\"title  title--xs \">\u0e07\u0e32\u0e19\u0e01\u0e32\u0e25\u0e48\u0e32 ICICI Prudential Life \u0e15\u0e35\u0e2b\u0e01\u0e17\u0e35\u0e48 Crown Melbourne<\/h3> <\/div><\/a><\/div><\/div><div class=\"swiper-slide\"><div class=\"card\"><a href=\"https:\/\/www.encore-apac.com\/th\/event-planning-resources\/case-studies\/destination-sales-incentive\/\"><div class=\"card__image\"><picture><source srcset=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/11\/Destination-Conference-Amway_360-degree-Screen-1200x813.webp\" type=\"image\/webp\"><img decoding=\"async\" src=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/11\/Destination-Conference-Amway_360-degree-Screen-1200x813.jpg\" loading=\"lazy\" alt=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/11\/Destination-Conference-Amway_360-degree-Screen-1200x813.jpg\"><\/picture><\/div><div class=\"card__text\"><h3 class=\"title  title--xs \">\u0e41\u0e2d\u0e21\u0e40\u0e27\u0e22\u0e4c \u0e44\u0e0a\u0e19\u0e48\u0e32 \u0e41\u0e04\u0e19\u0e2a\u0e4c \u0e2d\u0e34\u0e19\u0e08\u0e39\u0e07\u0e43\u0e08 \u0e21\u0e2d\u0e1a\u0e1b\u0e23\u0e32\u0e01\u0e0f\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e42\u0e25\u0e01<\/h3> <\/div><\/a><\/div><\/div><\/div><\/div><\/div><div class=\"swiper-elements\"><div class=\"cards-slider-button-prev\"><svg class=\"js-downloadSVG\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-labelledby=\"svgTitle svgDesc\"><title id=\"svgTitle\">arrow caret left<\/title><desc id=\"svgDesc\">arrow caret left icon<\/desc><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M14.7071 6.29289C15.0976 6.68342 15.0976 7.31658 14.7071 7.70711L10.4142 12L14.7071 16.2929C15.0976 16.6834 15.0976 17.3166 14.7071 17.7071C14.3166 18.0976 13.6834 18.0976 13.2929 17.7071L8.29289 12.7071C7.90237 12.3166 7.90237 11.6834 8.29289 11.2929L13.2929 6.29289C13.6834 5.90237 14.3166 5.90237 14.7071 6.29289Z\" fill=\"#1F1646\"><\/path><\/svg><\/div><div class=\"cards-slider-button-next\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-labelledby=\"svgTitle svgDesc\"><title id=\"svgTitle\">arrow caret right<\/title><desc id=\"svgDesc\">arrow caret right icon<\/desc><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M8.29289 6.29289C7.90237 6.68342 7.90237 7.31658 8.29289 7.70711L12.5858 12L8.29289 16.2929C7.90237 16.6834 7.90237 17.3166 8.29289 17.7071C8.68342 18.0976 9.31658 18.0976 9.70711 17.7071L14.7071 12.7071C15.0976 12.3166 15.0976 11.6834 14.7071 11.2929L9.70711 6.29289C9.31658 5.90237 8.68342 5.90237 8.29289 6.29289Z\" fill=\"#1F1646\"><\/path><\/svg><\/div><\/div><\/div><\/section> <\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":10,"featured_media":22577,"menu_order":0,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"tags":[492,985,1116,1008,1117],"class_list":["post-22558","case-study","type-case-study","status-publish","has-post-thumbnail","hentry","tag-led-wall-th","tag-985","tag-1116","tag-1008","tag-1117"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2d\u0e2d\u0e2a\u0e40\u0e15\u0e23\u0e40\u0e25\u0e35\u0e22\u0e40\u0e01\u0e32\u0e2b\u0e25\u0e35 | Encore\u00ae<\/title>\n<meta name=\"description\" content=\"\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e14\u0e37\u0e48\u0e21\u0e14\u0e48\u0e4d\u0e32\u0e04\u0e37\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48 Encore \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e02\u0e36\u0e49\u0e19\u0e2a\u0e4d\u0e32\u0e2b\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19 Australia Korea Business Awards \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e09\u0e25\u0e34\u0e21\u0e09\u0e25\u0e2d\u0e07... | \u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c\u0e44\u0e2e\u0e41\u0e2d\u0e17 \u0e42\u0e0b\u0e25 .\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.encore-apac.com\/th\/event-planning-resources\/case-studies\/australia-korea-business-awards\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2d\u0e2d\u0e2a\u0e40\u0e15\u0e23\u0e40\u0e25\u0e35\u0e22\u0e40\u0e01\u0e32\u0e2b\u0e25\u0e35\" \/>\n<meta property=\"og:description\" content=\"\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e14\u0e37\u0e48\u0e21\u0e14\u0e48\u0e4d\u0e32\u0e04\u0e37\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48 Encore \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e02\u0e36\u0e49\u0e19\u0e2a\u0e4d\u0e32\u0e2b\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19 Australia Korea Business Awards \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e09\u0e25\u0e34\u0e21\u0e09\u0e25\u0e2d\u0e07... | \u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c\u0e44\u0e2e\u0e41\u0e2d\u0e17 \u0e42\u0e0b\u0e25 .\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.encore-apac.com\/th\/event-planning-resources\/case-studies\/australia-korea-business-awards\/\" \/>\n<meta property=\"og:site_name\" content=\"Encore\u00ae\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EncoreEventTechnologiesAPAC\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-14T02:51:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Australia-Day-Celebration-Korea-2020-1536x1040-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"1040\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@EncoreGlobal_\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.encore-apac.com\\\/th\\\/event-planning-resources\\\/case-studies\\\/australia-korea-business-awards\\\/\",\"url\":\"https:\\\/\\\/www.encore-apac.com\\\/th\\\/event-planning-resources\\\/case-studies\\\/australia-korea-business-awards\\\/\",\"name\":\"\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2d\u0e2d\u0e2a\u0e40\u0e15\u0e23\u0e40\u0e25\u0e35\u0e22\u0e40\u0e01\u0e32\u0e2b\u0e25\u0e35 | Encore\u00ae\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.encore-apac.com\\\/th\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.encore-apac.com\\\/th\\\/event-planning-resources\\\/case-studies\\\/australia-korea-business-awards\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.encore-apac.com\\\/th\\\/event-planning-resources\\\/case-studies\\\/australia-korea-business-awards\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.encore-apac.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Australia-Day-Celebration-Korea-2020-1536x1040-1.jpg\",\"datePublished\":\"2020-04-14T02:47:00+00:00\",\"dateModified\":\"2026-01-14T02:51:20+00:00\",\"description\":\"\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e14\u0e37\u0e48\u0e21\u0e14\u0e48\u0e4d\u0e32\u0e04\u0e37\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48 Encore \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e02\u0e36\u0e49\u0e19\u0e2a\u0e4d\u0e32\u0e2b\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19 Australia Korea Business Awards \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e09\u0e25\u0e34\u0e21\u0e09\u0e25\u0e2d\u0e07... | \u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c\u0e44\u0e2e\u0e41\u0e2d\u0e17 \u0e42\u0e0b\u0e25 .\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.encore-apac.com\\\/th\\\/event-planning-resources\\\/case-studies\\\/australia-korea-business-awards\\\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.encore-apac.com\\\/th\\\/event-planning-resources\\\/case-studies\\\/australia-korea-business-awards\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/www.encore-apac.com\\\/th\\\/event-planning-resources\\\/case-studies\\\/australia-korea-business-awards\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.encore-apac.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Australia-Day-Celebration-Korea-2020-1536x1040-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.encore-apac.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Australia-Day-Celebration-Korea-2020-1536x1040-1.jpg\",\"width\":1536,\"height\":1040},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.encore-apac.com\\\/th\\\/event-planning-resources\\\/case-studies\\\/australia-korea-business-awards\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0e2b\u0e19\u0e49\u0e32\u0e41\u0e23\u0e01\",\"item\":\"https:\\\/\\\/www.encore-apac.com\\\/th\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2d\u0e2d\u0e2a\u0e40\u0e15\u0e23\u0e40\u0e25\u0e35\u0e22\u0e40\u0e01\u0e32\u0e2b\u0e25\u0e35\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.encore-apac.com\\\/th\\\/#website\",\"url\":\"https:\\\/\\\/www.encore-apac.com\\\/th\\\/\",\"name\":\"Encore\u00ae\",\"description\":\"Events That Transform\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.encore-apac.com\\\/th\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.encore-apac.com\\\/th\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.encore-apac.com\\\/th\\\/#organization\",\"name\":\"Encore\u00ae\",\"url\":\"https:\\\/\\\/www.encore-apac.com\\\/th\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/www.encore-apac.com\\\/th\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.encore-apac.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/encore-logo-e1743947984637.png\",\"contentUrl\":\"https:\\\/\\\/www.encore-apac.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/encore-logo-e1743947984637.png\",\"width\":1202,\"height\":330,\"caption\":\"Encore\u00ae\"},\"image\":{\"@id\":\"https:\\\/\\\/www.encore-apac.com\\\/th\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EncoreEventTechnologiesAPAC\",\"https:\\\/\\\/x.com\\\/EncoreGlobal_\",\"https:\\\/\\\/www.instagram.com\\\/encoreapac\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/encore-event-technologies-apac\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2d\u0e2d\u0e2a\u0e40\u0e15\u0e23\u0e40\u0e25\u0e35\u0e22\u0e40\u0e01\u0e32\u0e2b\u0e25\u0e35 | Encore\u00ae","description":"\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e14\u0e37\u0e48\u0e21\u0e14\u0e48\u0e4d\u0e32\u0e04\u0e37\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48 Encore \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e02\u0e36\u0e49\u0e19\u0e2a\u0e4d\u0e32\u0e2b\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19 Australia Korea Business Awards \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e09\u0e25\u0e34\u0e21\u0e09\u0e25\u0e2d\u0e07... | \u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c\u0e44\u0e2e\u0e41\u0e2d\u0e17 \u0e42\u0e0b\u0e25 .","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.encore-apac.com\/th\/event-planning-resources\/case-studies\/australia-korea-business-awards\/","og_locale":"th_TH","og_type":"article","og_title":"\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2d\u0e2d\u0e2a\u0e40\u0e15\u0e23\u0e40\u0e25\u0e35\u0e22\u0e40\u0e01\u0e32\u0e2b\u0e25\u0e35","og_description":"\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e14\u0e37\u0e48\u0e21\u0e14\u0e48\u0e4d\u0e32\u0e04\u0e37\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48 Encore \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e02\u0e36\u0e49\u0e19\u0e2a\u0e4d\u0e32\u0e2b\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19 Australia Korea Business Awards \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e09\u0e25\u0e34\u0e21\u0e09\u0e25\u0e2d\u0e07... | \u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c\u0e44\u0e2e\u0e41\u0e2d\u0e17 \u0e42\u0e0b\u0e25 .","og_url":"https:\/\/www.encore-apac.com\/th\/event-planning-resources\/case-studies\/australia-korea-business-awards\/","og_site_name":"Encore\u00ae","article_publisher":"https:\/\/www.facebook.com\/EncoreEventTechnologiesAPAC","article_modified_time":"2026-01-14T02:51:20+00:00","og_image":[{"width":1536,"height":1040,"url":"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Australia-Day-Celebration-Korea-2020-1536x1040-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@EncoreGlobal_","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.encore-apac.com\/th\/event-planning-resources\/case-studies\/australia-korea-business-awards\/","url":"https:\/\/www.encore-apac.com\/th\/event-planning-resources\/case-studies\/australia-korea-business-awards\/","name":"\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2d\u0e2d\u0e2a\u0e40\u0e15\u0e23\u0e40\u0e25\u0e35\u0e22\u0e40\u0e01\u0e32\u0e2b\u0e25\u0e35 | Encore\u00ae","isPartOf":{"@id":"https:\/\/www.encore-apac.com\/th\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.encore-apac.com\/th\/event-planning-resources\/case-studies\/australia-korea-business-awards\/#primaryimage"},"image":{"@id":"https:\/\/www.encore-apac.com\/th\/event-planning-resources\/case-studies\/australia-korea-business-awards\/#primaryimage"},"thumbnailUrl":"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Australia-Day-Celebration-Korea-2020-1536x1040-1.jpg","datePublished":"2020-04-14T02:47:00+00:00","dateModified":"2026-01-14T02:51:20+00:00","description":"\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e14\u0e37\u0e48\u0e21\u0e14\u0e48\u0e4d\u0e32\u0e04\u0e37\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48 Encore \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e02\u0e36\u0e49\u0e19\u0e2a\u0e4d\u0e32\u0e2b\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19 Australia Korea Business Awards \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e09\u0e25\u0e34\u0e21\u0e09\u0e25\u0e2d\u0e07... | \u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c\u0e44\u0e2e\u0e41\u0e2d\u0e17 \u0e42\u0e0b\u0e25 .","breadcrumb":{"@id":"https:\/\/www.encore-apac.com\/th\/event-planning-resources\/case-studies\/australia-korea-business-awards\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.encore-apac.com\/th\/event-planning-resources\/case-studies\/australia-korea-business-awards\/"]}]},{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.encore-apac.com\/th\/event-planning-resources\/case-studies\/australia-korea-business-awards\/#primaryimage","url":"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Australia-Day-Celebration-Korea-2020-1536x1040-1.jpg","contentUrl":"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2026\/01\/Australia-Day-Celebration-Korea-2020-1536x1040-1.jpg","width":1536,"height":1040},{"@type":"BreadcrumbList","@id":"https:\/\/www.encore-apac.com\/th\/event-planning-resources\/case-studies\/australia-korea-business-awards\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0e2b\u0e19\u0e49\u0e32\u0e41\u0e23\u0e01","item":"https:\/\/www.encore-apac.com\/th\/"},{"@type":"ListItem","position":2,"name":"\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2d\u0e2d\u0e2a\u0e40\u0e15\u0e23\u0e40\u0e25\u0e35\u0e22\u0e40\u0e01\u0e32\u0e2b\u0e25\u0e35"}]},{"@type":"WebSite","@id":"https:\/\/www.encore-apac.com\/th\/#website","url":"https:\/\/www.encore-apac.com\/th\/","name":"Encore\u00ae","description":"Events That Transform","publisher":{"@id":"https:\/\/www.encore-apac.com\/th\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.encore-apac.com\/th\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":"Organization","@id":"https:\/\/www.encore-apac.com\/th\/#organization","name":"Encore\u00ae","url":"https:\/\/www.encore-apac.com\/th\/","logo":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.encore-apac.com\/th\/#\/schema\/logo\/image\/","url":"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/04\/encore-logo-e1743947984637.png","contentUrl":"https:\/\/www.encore-apac.com\/wp-content\/uploads\/2025\/04\/encore-logo-e1743947984637.png","width":1202,"height":330,"caption":"Encore\u00ae"},"image":{"@id":"https:\/\/www.encore-apac.com\/th\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EncoreEventTechnologiesAPAC","https:\/\/x.com\/EncoreGlobal_","https:\/\/www.instagram.com\/encoreapac\/","https:\/\/www.linkedin.com\/company\/encore-event-technologies-apac\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.encore-apac.com\/th\/wp-json\/wp\/v2\/case-study\/22558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encore-apac.com\/th\/wp-json\/wp\/v2\/case-study"}],"about":[{"href":"https:\/\/www.encore-apac.com\/th\/wp-json\/wp\/v2\/types\/case-study"}],"author":[{"embeddable":true,"href":"https:\/\/www.encore-apac.com\/th\/wp-json\/wp\/v2\/users\/10"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.encore-apac.com\/th\/wp-json\/wp\/v2\/media\/22577"}],"wp:attachment":[{"href":"https:\/\/www.encore-apac.com\/th\/wp-json\/wp\/v2\/media?parent=22558"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encore-apac.com\/th\/wp-json\/wp\/v2\/tags?post=22558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}